{"id":174,"date":"2022-06-10T20:53:18","date_gmt":"2022-06-10T20:53:18","guid":{"rendered":"https:\/\/kadence.pixel-show.com\/cleaning-services\/?p=174"},"modified":"2023-12-09T07:50:15","modified_gmt":"2023-12-09T12:50:15","slug":"overcoming-removal-orders-your-path-to-a-successful-remedy","status":"publish","type":"post","link":"https:\/\/ibavocate.ca\/fr\/overcoming-removal-orders-your-path-to-a-successful-remedy\/","title":{"rendered":"Surmonter les mesures d'\u00e9loignement : Votre chemin vers un recours fructueux"},"content":{"rendered":"<p>Dans le paysage complexe de l'immigration, l'\u00e9mission d'une mesure d'expulsion peut constituer un revers d\u00e9courageant. Toutefois, pour les personnes confront\u00e9es \u00e0 cette situation au Canada, il existe des moyens de faire appel avec succ\u00e8s et de tracer la voie vers un avenir s\u00fbr. Cet article examine le processus d'annulation des mesures d'\u00e9loignement et met en lumi\u00e8re les options disponibles pour les personnes d\u00e9termin\u00e9es \u00e0 rester dans le pays qu'elles consid\u00e8rent d\u00e9sormais comme leur foyer.<\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-15fd9f2efb45c639b514e915cee66017\"><strong>Comprendre les mesures de renvoi<\/strong><\/p>\n\n\n\n<p>Une mesure de renvoi est une directive l\u00e9gale \u00e9mise par l'Agence des services frontaliers du Canada (ASFC) exigeant qu'une personne quitte le pays. Il existe trois types de mesures de renvoi :<\/p>\n\n\n\n<p><strong>Ordre de d\u00e9part :&nbsp;<\/strong>Cette ordonnance oblige une personne \u00e0 quitter le Canada dans un d\u00e9lai d\u00e9termin\u00e9. Aucune sanction financi\u00e8re ou l\u00e9gale n'est associ\u00e9e \u00e0 cette ordonnance, mais le non-respect de cette derni\u00e8re peut entra\u00eener une interdiction de retour pour une p\u00e9riode pouvant aller jusqu'\u00e0 un an.<\/p>\n\n\n\n<p><strong>Ordre d'exclusion :&nbsp;<\/strong>Les personnes qui font l'objet d'une mesure d'exclusion doivent quitter le Canada et n'ont pas le droit d'y revenir pendant une p\u00e9riode d\u00e9termin\u00e9e, g\u00e9n\u00e9ralement de deux \u00e0 cinq ans. Pour revenir pendant cette p\u00e9riode, il faut obtenir l'autorisation d'un agent d'immigration.<\/p>\n\n\n\n<p><strong>Ordre d'expulsion :<\/strong>&nbsp;La mesure d'expulsion, la plus grave des trois, impose le renvoi d'une personne ayant fait l'objet d'une condamnation p\u00e9nale grave. Les personnes faisant l'objet d'une mesure d'expulsion peuvent se voir interdire de fa\u00e7on permanente de revenir au Canada.<\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-8d18afed6b6532052091ad9c24338f61\"><strong>Chercher un rem\u00e8de<\/strong><\/p>\n\n\n\n<p>Il existe plusieurs voies de recours pour les personnes souhaitant annuler ou contester un arr\u00eat\u00e9 d'expulsion :<\/p>\n\n\n\n<p><strong>Recours devant la Section d'appel de l'immigration (SAI) :<\/strong>&nbsp;Selon le type de mesure d'\u00e9loignement, les personnes peuvent avoir le droit de faire appel aupr\u00e8s de l'IAD. Il s'agit de fournir des preuves et des arguments expliquant pourquoi la mesure devrait \u00eatre annul\u00e9e ou suspendue.<\/p>\n\n\n\n<p><strong>\u00c9valuation des risques avant renvoi (ERAR) :<\/strong>&nbsp;Pour des raisons humanitaires, les personnes menac\u00e9es d'expulsion peuvent demander un ERAR, qui \u00e9value le risque qu'elles encourent si elles sont expuls\u00e9es vers leur pays d'origine.<\/p>\n\n\n\n<p><strong>Demande de contr\u00f4le judiciaire :&nbsp;<\/strong>Si l'appel ou l'ERAR n'aboutit pas, les personnes peuvent demander \u00e0 la Cour f\u00e9d\u00e9rale de proc\u00e9der \u00e0 un contr\u00f4le judiciaire. Il s'agit d'un examen juridique du processus d\u00e9cisionnel afin de s'assurer qu'il a \u00e9t\u00e9 \u00e9quitable et conforme \u00e0 la loi.<\/p>\n\n\n\n<p><strong>Suspension temporaire de l'expulsion :&nbsp;<\/strong>Dans certains cas, les personnes peuvent demander un sursis temporaire \u00e0 l'ex\u00e9cution de la mesure d'\u00e9loignement, ce qui leur permet de rester au Canada pendant l'examen de leur dossier.<\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-fb395411274c2e5d668b48fc1c952b08\"><strong>Legal representation and timely action<\/strong><\/p>\n\n\n\n<p>Navigating the process of overturning a deportation order can be complex and demanding. Legal representation is often essential to ensure that all available appeals are explored and arguments are effectively presented. Time is of the essence as there are strict time limits for filing appeals and applications for review.<\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-e7b8ee6513f3398872b1120906ea02c5\"><strong>Une voie \u00e0 suivre<\/strong><\/p>\n\n\n\n<p>Bien qu'une mesure d'\u00e9loignement puisse \u00eatre p\u00e9nible, ce n'est pas n\u00e9cessairement la fin de la route. Le syst\u00e8me d'immigration canadien reconna\u00eet les complexit\u00e9s et les incertitudes auxquelles sont confront\u00e9s les individus et pr\u00e9voit des m\u00e9canismes de recours. En comprenant les options disponibles et en recherchant une assistance professionnelle, les personnes peuvent s'efforcer de s'assurer un avenir dans le pays qu'elles appellent leur foyer.<\/p>\n\n\n\n<p>N'oubliez pas que le chemin \u00e0 parcourir pour surmonter une mesure d'\u00e9loignement peut \u00eatre sem\u00e9 d'emb\u00fbches, mais avec de la d\u00e9termination, des conseils juridiques et la mise en \u0153uvre des recours disponibles, les personnes peuvent trouver la voie de la stabilit\u00e9 et d'un nouveau d\u00e9part au Canada.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dans le paysage complexe de l'immigration, l'\u00e9mission d'un ordre d'expulsion peut \u00eatre un revers d\u00e9courageant....<\/p>","protected":false},"author":1,"featured_media":967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":true,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"slim_seo":[],"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/posts\/174"}],"collection":[{"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":3,"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/posts\/174\/revisions"}],"predecessor-version":[{"id":965,"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/posts\/174\/revisions\/965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/media\/967"}],"wp:attachment":[{"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/media?parent=174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/categories?post=174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibavocate.ca\/fr\/wp-json\/wp\/v2\/tags?post=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}